{"id":5645,"date":"2021-12-01T08:36:20","date_gmt":"2021-12-01T07:36:20","guid":{"rendered":"https:\/\/schoolplasticfreemovement.org\/?p=5645"},"modified":"2021-12-03T14:09:01","modified_gmt":"2021-12-03T13:09:01","slug":"las-actividades-docentes-del-programa-spem-de-nuevo-en-marcha-en-la-noche-de-los-investigadores","status":"publish","type":"post","link":"https:\/\/schoolplasticfreemovement.org\/tr\/las-actividades-docentes-del-programa-spem-de-nuevo-en-marcha-en-la-noche-de-los-investigadores\/","title":{"rendered":"Las actividades docentes del programa SPEM, de nuevo en marcha en \u201cLa noche de los investigadores\u201d"},"content":{"rendered":"\n<div><div>\n<p>A finales del pasado mes de octubre, se llev\u00f3 a cabo en el centro municipal de ocio infantil y juvenil &#8220;La Estaci\u00f3n&#8221;, en Burgos (Espa\u00f1a), la primera iniciativa docente del programa SPEM. Se trata de un espacio real dirigido a estudiantes de Educaci\u00f3n Primaria interesados en el \u00e1mbito de la investigaci\u00f3n y de la sostenibilidad, dentro del programa establecido durante \u201cLa noche de los investigadores\u201d, iniciativa organizada desde la Unidad de Cultura Cient\u00edfica de la Universidad de Burgos.<\/p>\n<p>Como afirm\u00f3 la directora del CENIEH, el principal objetivo de esta iniciativa es mostrar la diversidad y el impacto de la ciencia en la vida cotidiana, presente en cualquiera de nuestras actividades, y comprender que este impacto hace nuestras vidas m\u00e1s plenas, adem\u00e1s de despertar vocaciones cient\u00edficas entre los m\u00e1s j\u00f3venes.<\/p>\n<p>Los profesores de la Universidad de Burgos, y miembros del equipo del proyecto SPEM (Schools Plastic freE Movement), se encargan durante estos meses de desarrollar iniciativas docentes con el objetivo de concienciar sobre el buen uso de los pl\u00e1sticos. Una vez dise\u00f1adas las unidades docentes, estas deben ser validadas en \u00e1mbitos de aplicaci\u00f3n reales. Esta iniciativa es la segunda acci\u00f3n de validaci\u00f3n que supone un gran avance para la implantaci\u00f3n de estas iniciativas en el \u00e1mbito acad\u00e9mico reglado. Los estudiantes se mostraron contentos de participar en esta iniciativa y los profesores pudieron cotejar la idoneidad de las actividades programadas, destacando puntos fuertes y de mejora para futuras implementaciones.<\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"5649\" data-permalink=\"https:\/\/schoolplasticfreemovement.org\/tr\/las-actividades-docentes-del-programa-spem-de-nuevo-en-marcha-en-la-noche-de-los-investigadores\/diapositiva1\/\" data-orig-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/12\/Diapositiva1.jpg?fit=1280%2C720&amp;ssl=1\" data-orig-size=\"1280,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Diapositiva1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/12\/Diapositiva1.jpg?fit=640%2C360&amp;ssl=1\" class=\" wp-image-5649 aligncenter\" src=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/12\/Diapositiva1-300x169.jpg?resize=517%2C291\" alt=\"\" width=\"517\" height=\"291\" srcset=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/12\/Diapositiva1.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/12\/Diapositiva1.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/12\/Diapositiva1.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/12\/Diapositiva1.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"(max-width: 517px) 100vw, 517px\" \/><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4293,"featured_media":334,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[26,70],"tags":[],"class_list":["post-5645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-scuole-senza-plastica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2019\/07\/cropped-Bulb1.jpg?fit=1000%2C250&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbDhrA-1t3","_links":{"self":[{"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/posts\/5645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/users\/4293"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/comments?post=5645"}],"version-history":[{"count":2,"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/posts\/5645\/revisions"}],"predecessor-version":[{"id":5650,"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/posts\/5645\/revisions\/5650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/media\/334"}],"wp:attachment":[{"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/media?parent=5645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/categories?post=5645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/tr\/wp-json\/wp\/v2\/tags?post=5645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}