{"id":5750,"date":"2021-12-15T11:21:37","date_gmt":"2021-12-15T10:21:37","guid":{"rendered":"https:\/\/schoolplasticfreemovement.org\/?p=5750"},"modified":"2021-12-15T14:45:23","modified_gmt":"2021-12-15T13:45:23","slug":"actividad-spem-identificacion-de-plasticos","status":"publish","type":"post","link":"https:\/\/schoolplasticfreemovement.org\/pt\/actividad-spem-identificacion-de-plasticos\/","title":{"rendered":"Actividad SPEM: Identificaci\u00f3n de pl\u00e1sticos"},"content":{"rendered":"\n<div><div>\n<div>\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/06\/SPEM_WebBanner.gif?resize=569%2C180\" \/><\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 12px;\"><em>Esta actividad ha sido realizada por la profesora\u00a0<strong>Miriam Trigo L\u00f3pez<\/strong>\u00a0dentro de la<\/em><\/span><br \/><span style=\"font-size: 12px;\"><em>unidad did\u00e1ctica \u201cDetectives por la sostenibilidad\u201d, llevada a cabo en Burgos (Espa\u00f1a)<\/em><\/span><br \/><span style=\"font-size: 12px;\"><em>durante los meses de octubre y noviembre de 2021.<\/em><\/span><\/p>\n<table style=\"border-style: solid; width: 100%; border-color: #000000;\" width=\"100%\">\n<tbody>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>T\u00edtulo de la actividad \/ pr\u00e1ctica<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Identificaci\u00f3n de pl\u00e1sticos<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Origen de la actividad<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Esta actividad se imparte como introducci\u00f3n del taller \u201cDetectives por la sostenibilidad\u201d, que trata sobre el uso de los pl\u00e1sticos y la mala gesti\u00f3n de los residuos.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Edad de los estudiantes<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a06\u00ba de Educaci\u00f3n Primaria y 1\u00ba de Educaci\u00f3n Secundaria<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Grupo objetivo (tipo de alumnos, tama\u00f1o del grupo)<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Alumnos de altas capacidades. 10 alumnos por grupo<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Asignaturas escolares + temas afectados<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Ciencias de la Naturaleza<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Objetivos educativos de la pr\u00e1ctica<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Ense\u00f1ar a los alumnos las distintas aplicaciones de los pl\u00e1sticos en la vida diaria m\u00e1s all\u00e1 de sus aplicaciones de un solo uso. Ense\u00f1arles a distinguir distintos tipos de pl\u00e1stico por sus caracter\u00edsticas, densidad, comportamiento a la llama, sonido y aplicaci\u00f3n.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Duraci\u00f3n<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a01 hora y 45 minutos<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Lugar<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0I.E.S. Conde Diego Porcelos<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Materiales \/ Recursos \/ requisitos t\u00e9cnicos<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Laboratorio de Qu\u00edmica<\/p>\n<p>Materiales de laboratorio:<\/p>\n<p>\u2013\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Residuos de pl\u00e1sticos de aplicaciones comunes (PET, PE, PP, PVC, PS)<\/p>\n<p>\u2013\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Mechero Bunsen<\/p>\n<p>\u2013\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pinzas<\/p>\n<p>\u2013\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Cristalizadores<\/p>\n<p>\u2013\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Disoluciones acuosas de CaCl<sub>2\u00a0<\/sub>de distinta densidad.<\/p>\n<p>Materiales para los alumnos:<\/p>\n<p>\u2013\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tabla para rellenar en el aula con las observaciones de las demostraciones (Anexo I)<\/p>\n<p>\u2013\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Esquema de determinaci\u00f3n de pol\u00edmeros (Anexo II)<\/p>\n<p>\u2013\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tabla con los s\u00edmbolos de reciclaje, nombre, estructura y acr\u00f3nimos de los pol\u00edmeros (Anexo III).<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" rowspan=\"4\" width=\"18%\">\n<p><strong>Descripci\u00f3n de la actividad<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Preparaci\u00f3n:<\/p>\n<p>Se lanzan las preguntas: \u00bfQu\u00e9 sab\u00e9is de los pl\u00e1sticos? y \u00bfqu\u00e9 cosas est\u00e1n hechas de pl\u00e1stico?<\/p>\n<p>Los alumnos suelen responder que los pl\u00e1sticos son malos porque contaminan, y la mayor\u00eda de los ejemplos que nombrar\u00e1n los alumnos ser\u00e1n referentes a pl\u00e1sticos de un solo uso. Los alumnos van nombrando distintos de usos de los pl\u00e1sticos, que el profesor completar\u00e1 con ejemplos menos conocidos o de objetos de los que se piensa que son de otro material. Se menciona tambi\u00e9n la importancia, los beneficios y las limitaciones de los pl\u00e1sticos frente a otros materiales, de tal manera que se les orienta a darse cuenta de que el problema no son los pl\u00e1sticos sino lo que hacemos con los residuos. Se tratar\u00e1 tambi\u00e9n de concienciar sobre la problem\u00e1tica a nivel mundial que ello supone.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>Fase principal:<\/p>\n<p>A modo de demostraci\u00f3n por parte del profesor para evitar accidentes, se mostrar\u00e1n una serie de pl\u00e1sticos de cada tipo utilizados para distintas aplicaciones (los lleva el profesor), se hablar\u00e1 de sus caracter\u00edsticas f\u00edsicas, su sonido, de sus aplicaciones y se determinar\u00e1 su densidad respecto al agua y a disoluciones de CaCl<sub>2<\/sub>\u00a0de distinta densidad, se observar\u00e1 su comportamiento a la llama y se tratar\u00e1 de identificar de qu\u00e9 pol\u00edmero se trata mediante el esquema de determinaci\u00f3n de pol\u00edmeros (Anexo II). Tambi\u00e9n se hablar\u00e1 de otros temas relacionados con su uso, desarrollo y an\u00e9cdotas sobre sus aplicaciones. Se anotar\u00e1n las observaciones en la tabla (Anexo I), se determinar\u00e1 su nombre y su n\u00famero de reciclaje. Adem\u00e1s de los pol\u00edmeros con n\u00fameros de reciclaje 1-6, se mostrar\u00e1n algunos ejemplos de pl\u00e1sticos del 7, junto con las aplicaciones que tienen.<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Aplicaciones: Ser\u00e1 importante mencionar durante las demostraciones que un mismo pl\u00e1stico puede tener muchas aplicaciones distintas, y que varios tipos de pl\u00e1stico pueden servir para una misma aplicaci\u00f3n. Se enumerar\u00e1n las principales aplicaciones de cada tipo de pol\u00edmero.<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Densidad: Los pol\u00edmeros se colocar\u00e1n agua y en disoluciones acuosas de CaCl<sub>2<\/sub>\u00a0de densidad 1,17 y 1,45 g\/mL y se observar\u00e1 si flotan o se hunden.<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Comportamiento a la llama: Una peque\u00f1a cantidad de pl\u00e1stico se quemar\u00e1 a la llama de un mechero Bunsen y se observar\u00e1 tanto el color de la llama, el humo, el olor, si se apaga al retirarlo de la llama o si contin\u00faa ardiendo, etc.<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Aspecto f\u00edsico:<strong>\u00a0\u00a0<\/strong>Se observar\u00e1n los materiales tratando de evaluar de forma cualitativa sus propiedades f\u00edsicas, rigidez, flexibilidad, sonido, dureza\u2026<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 N\u00famero de reciclaje: En la mayor\u00eda de los pl\u00e1sticos viene impreso su n\u00famero de reciclaje o sus siglas. Con la tabla de n\u00fameros de reciclaje se puede identificar cada uno.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>Conclusiones:<\/p>\n<p>Se reflexionar\u00e1 sobre el uso de los pl\u00e1sticos, sus ventajas y sus limitaciones, poniendo \u00e9nfasis en sus beneficios para la sociedad, en la mala gesti\u00f3n de los residuos de los pl\u00e1sticos, y en la necesidad de reducir su uso, reutilizarlo y reciclar.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>Otros elementos (opcional):<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Evaluaci\u00f3n<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0El profesor quema una serie de pl\u00e1sticos desconocidos, y mediante las anotaciones que han hecho en la tabla del Anexo I, junto con el esquema de identificaci\u00f3n de pl\u00e1sticos (Anexo II), y la comparaci\u00f3n de densidades, tienen que ser capaces de identificarlos.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Enlace a recursos externos \u00fatiles (opcional)<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p><a href=\"https:\/\/universidaddeburgos-my.sharepoint.com\/personal\/mcorbi_ubu_es\/_layouts\/15\/onedrive.aspx?id=%2Fpersonal%2Fmcorbi%5Fubu%5Fes%2FDocuments%2FSPEM%20%2D%20School%20Plastic%20Free%20Movement%2F2021%5FActivities%20template%5FSPEM%2FImages%20%26%20resources%5FActivities%20SPEM%2FAnexos%20Sesi%C3%B3n%201%2E%20Identificaci%C3%B3n%20de%20pl%C3%A1sticos%2Epdf&amp;parent=%2Fpersonal%2Fmcorbi%5Fubu%5Fes%2FDocuments%2FSPEM%20%2D%20School%20Plastic%20Free%20Movement%2F2021%5FActivities%20template%5FSPEM%2FImages%20%26%20resources%5FActivities%20SPEM\">https:\/\/universidaddeburgos-my.sharepoint.com\/:b:\/g\/personal\/mcorbi_ubu_es\/EbxgZNcRXMhJsNItpahJiuUBTwfzMl2KizEmi3zSc4E_1g?e=Rf1aoO\u00a0<\/a><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Enlace a los resultados de la actividad (v\u00eddeo, fotos, proyectos, etc.)<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Consejos para educadores \/ antecedentes te\u00f3ricos o contexto curricular<\/strong><\/p>\n<p><strong><em>(opcional)<\/em><\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p><span class=\"NormalTextRun SCXW227288754 BCX0\">Es importante tener cierto conocimiento\u00a0<\/span><span class=\"NormalTextRun SCXW227288754 BCX0\">previo\u00a0<\/span><span class=\"NormalTextRun SCXW227288754 BCX0\">sobre los\u00a0<\/span><span class=\"NormalTextRun SCXW227288754 BCX0\">distintos tipos de pol\u00edmeros<\/span><span class=\"NormalTextRun SCXW227288754 BCX0\">, sus propiedades y su transformaci\u00f3n para poder relacionarlo con sus aplicaciones y poder poner m\u00e1s ejemplos de uso en la vida cotidiana, sobre todo con algunos tipos de pol\u00edmeros<\/span><span class=\"NormalTextRun SCXW227288754 BCX0\">. Adem\u00e1s, esto tambi\u00e9n es importante para poder recopilar materiales para quemarlos en el aula.<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4293,"featured_media":5700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[70,255,30],"tags":[],"class_list":["post-5750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuole-senza-plastica","category-activities-in-spain","category-activities"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/12\/plastic-waste-3576988_960_720.jpg?fit=960%2C528&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbDhrA-1uK","_links":{"self":[{"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/posts\/5750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/users\/4293"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/comments?post=5750"}],"version-history":[{"count":4,"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/posts\/5750\/revisions"}],"predecessor-version":[{"id":5777,"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/posts\/5750\/revisions\/5777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/media\/5700"}],"wp:attachment":[{"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/media?parent=5750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/categories?post=5750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/pt\/wp-json\/wp\/v2\/tags?post=5750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}