{"id":6681,"date":"2022-09-06T22:06:24","date_gmt":"2022-09-06T20:06:24","guid":{"rendered":"https:\/\/schoolplasticfreemovement.org\/?p=6681"},"modified":"2022-09-06T22:09:09","modified_gmt":"2022-09-06T20:09:09","slug":"proyecto-medioambiental-y-al-cole-en-bici","status":"publish","type":"post","link":"https:\/\/schoolplasticfreemovement.org\/lt\/proyecto-medioambiental-y-al-cole-en-bici\/","title":{"rendered":"Proyecto medioambiental. Y \u00a1al cole en bici!"},"content":{"rendered":"\n<p>Hay centros, entre ellos el <strong>CEIP El Peral<\/strong> de Valladolid, que tienen ya trayectoria en su sensibilidad y compromiso en el cuidado del medio ambiente. Su centro tiene un proyecto medioambiental que incluye la prevenci\u00f3n, reutilizaci\u00f3n y reciclaje de residuos, la agricultura ecol\u00f3gica con el huerto escolar, el ahorro y la gesti\u00f3n del agua.<\/p>\n<p>Tambi\u00e9n el cuidado del entorno inmediato, el consumo sostenible y el comercio justo.<\/p>\n<p>Este es el <a href=\"http:\/\/ceipelperal.centros.educa.jcyl.es\/sitio\/index.cgi?wid_seccion=35&amp;wid_item=205\" target=\"_blank\" rel=\"noopener\">enlace de su proyecto medioambiental<\/a> en el colegio<\/p>\n<p>Es muy interesante la iniciativa a la que se han unido \u201cAl cole en bici\u201d en el que se apuesta por una movilidad m\u00e1s sostenible tambi\u00e9n. En el centro han buscado el espacio donde poder aparcar las bicicletas de manera segura y tambi\u00e9n desarrollan actividades de educaci\u00f3n vial con la bicicleta.<\/p>\n<p>\u00a0<\/p>\n\n\n\n<div class=\"editor:no-inserter ext ext-p-lg wp-block-group alignfull ext-my-0\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"has-nested-images columns-default wp-block-gallery alignwide is-cropped editor:no-caption wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"356\" height=\"386\" data-attachment-id=\"6689\" data-permalink=\"https:\/\/schoolplasticfreemovement.org\/lt\/proyecto-medioambiental-y-al-cole-en-bici\/el-peral-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/El-Peral-1.jpg?fit=356%2C386&amp;ssl=1\" data-orig-size=\"356,386\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;marian&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1662501332&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"El-Peral-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/El-Peral-1.jpg?fit=356%2C386&amp;ssl=1\" data-id=\"6689\" src=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/El-Peral-1.jpg?resize=356%2C386&#038;ssl=1\" alt=\"\" class=\"wp-image-6689\" srcset=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/El-Peral-1.jpg?w=356&amp;ssl=1 356w, https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/El-Peral-1.jpg?resize=277%2C300&amp;ssl=1 277w\" sizes=\"(max-width: 356px) 100vw, 356px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"533\" data-attachment-id=\"6684\" data-permalink=\"https:\/\/schoolplasticfreemovement.org\/lt\/proyecto-medioambiental-y-al-cole-en-bici\/bici-02\/\" data-orig-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/bici-02.jpg?fit=686%2C571&amp;ssl=1\" data-orig-size=\"686,571\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;marian&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1662495762&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"bici 02\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/bici-02.jpg?fit=640%2C533&amp;ssl=1\" data-id=\"6684\" src=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/bici-02.jpg?resize=640%2C533\" alt=\"\" class=\"wp-image-6684\" srcset=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/bici-02.jpg?w=686&amp;ssl=1 686w, https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/bici-02.jpg?resize=300%2C250&amp;ssl=1 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/figure>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3529,"featured_media":6683,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[30,70,255],"tags":[249,321,322],"class_list":["post-6681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activities","category-scuole-senza-plastica","category-activities-in-spain","tag-plastic-free","tag-bici","tag-ecomovilidad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2022\/09\/bici-01.jpg?fit=900%2C675&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbDhrA-1JL","_links":{"self":[{"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/posts\/6681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/users\/3529"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/comments?post=6681"}],"version-history":[{"count":3,"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/posts\/6681\/revisions"}],"predecessor-version":[{"id":6690,"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/posts\/6681\/revisions\/6690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/media\/6683"}],"wp:attachment":[{"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/media?parent=6681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/categories?post=6681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/lt\/wp-json\/wp\/v2\/tags?post=6681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}