{"id":7346,"date":"2023-02-23T17:49:13","date_gmt":"2023-02-23T16:49:13","guid":{"rendered":"https:\/\/schoolplasticfreemovement.org\/?p=7346"},"modified":"2024-09-03T17:17:02","modified_gmt":"2024-09-03T15:17:02","slug":"young-scientists-who-save-the-planet-earth","status":"publish","type":"post","link":"https:\/\/schoolplasticfreemovement.org\/es\/young-scientists-who-save-the-planet-earth\/","title":{"rendered":"Concorso per Giovani scienziati che vogliono salvare il pianeta"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7346\" class=\"elementor elementor-7346\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7accab9 elementor-section-content-space-between elementor-section-boxed ang-section-padding-initial elementor-section-height-default elementor-section-height-default elementor-repeater-item-none elementor-repeater-item-none_hover\" data-id=\"7accab9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2313dbe elementor-repeater-item-none elementor-repeater-item-none_hover\" data-id=\"2313dbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7eabee3 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"7eabee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Giovani scienziati che vogliono salvare  il pianeta<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c3679e elementor-section-boxed ang-section-padding-initial elementor-section-height-default elementor-section-height-default elementor-repeater-item-none elementor-repeater-item-none_hover\" data-id=\"9c3679e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3628328 elementor-repeater-item-none elementor-repeater-item-none_hover\" data-id=\"3628328\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9ad0ad external_elementor-repeater-item-none_external elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-image\" data-id=\"c9ad0ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"7348\" data-permalink=\"https:\/\/schoolplasticfreemovement.org\/es\/young-scientists-who-save-the-planet-earth\/bambini-esplosione\/\" data-orig-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2023\/01\/bambini-esplosione.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"bambini esplosione\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2023\/01\/bambini-esplosione.jpg?fit=500%2C500&amp;ssl=1\" width=\"500\" height=\"500\" src=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2023\/01\/bambini-esplosione.jpg?fit=500%2C500&amp;ssl=1\" class=\"attachment-medium_large size-medium_large wp-image-7348\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2023\/01\/bambini-esplosione.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2023\/01\/bambini-esplosione.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2023\/01\/bambini-esplosione.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2023\/01\/bambini-esplosione.jpg?resize=50%2C50&amp;ssl=1 50w\" sizes=\"(max-width: 500px) 100vw, 500px\" data-attachment-id=\"7348\" data-permalink=\"https:\/\/schoolplasticfreemovement.org\/mk\/young-scientists-who-save-the-planet-earth\/bambini-esplosione\/\" data-orig-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2023\/01\/bambini-esplosione.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"bambini esplosione\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2023\/01\/bambini-esplosione.jpg?fit=500%2C500&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da5152a elementor-section-boxed ang-section-padding-initial elementor-section-height-default elementor-section-height-default elementor-repeater-item-none elementor-repeater-item-none_hover\" data-id=\"da5152a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07f9f55 elementor-repeater-item-none elementor-repeater-item-none_hover\" data-id=\"07f9f55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7eda1e0 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"7eda1e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>All&#8217;interno della cornice del progetto europeo SPEM &#8211; School Plastic FreE Movement nasce il nuovo concorso intitolato \u00abGiovani scienziati che vogliono salvare il pianeta\u00bb.<\/p><p>Scopri nel dettaglio l&#8217;iniziativa!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d3fe17 elementor-section-boxed ang-section-padding-initial elementor-section-height-default elementor-section-height-default elementor-repeater-item-none elementor-repeater-item-none_hover\" data-id=\"4d3fe17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1da9245 elementor-repeater-item-none elementor-repeater-item-none_hover\" data-id=\"1da9245\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36a521a elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-eael-interactive-circle\" data-id=\"36a521a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"eael-interactive-circle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div id=\"eael-interactive-circle-36a521a\" class=\"eael-interactive-circle\" data-tabid=\"36a521a\">\n\t\t\t                <div class=\"eael-circle-wrapper eael-interactive-circle-preset-1 eael-interactive-circle-event-hover eael-circle-responsive-view\" data-appearance=\"eael-interactive-circle-animation-1\" data-autoplay=\"0\" data-autoplay-interval=\"2000\">\n                    <div class=\"eael-circle-info\" data-items=\"6\">\n                        <div class=\"eael-circle-inner\">\n\t\t\t\t\t\t\t                                <div class=\"eael-circle-item elementor-repeater-item-fe05459\">\n                                    <div aria-controls=\"eael-interactive-1\" tabindex=\"0\" class=\"eael-circle-btn \" id=\"eael-circle-item-1\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<!-- Start URL support -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-btn-icon classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-icon-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-leaf\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M546.2 9.7c-5.6-12.5-21.6-13-28.3-1.2C486.9 62.4 431.4 96 368 96h-80C182 96 96 182 96 288c0 7 .8 13.7 1.5 20.5C161.3 262.8 253.4 224 384 224c8.8 0 16 7.2 16 16s-7.2 16-16 16C132.6 256 26 410.1 2.4 468c-6.6 16.3 1.2 34.9 17.5 41.6 16.4 6.8 35-1.1 41.8-17.3 1.5-3.6 20.9-47.9 71.9-90.6 32.4 43.9 94 85.8 174.9 77.2C465.5 467.5 576 326.7 576 154.3c0-50.2-10.8-102.2-29.8-144.6z\"><\/path><\/svg><span class=\"eael-circle-btn-txt\">Obiettivi<\/span>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                                        \t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- End URL support -->\n                                        \n                                    <\/div>\n                                    <div id=\"eael-interactive-1\" aria-labelledby=\"eael-circle-item-1\" class=\"eael-circle-btn-content eael-circle-item-1 \">\n                                        <div class=\"eael-circle-content\">\n\t\t\t\t\t\t\t\t\t\t\t<p>1.Educare i bambini ad evitare il pi\u00f9 possibile l&#8217;uso della plastica\u00a0<br \/>2.Sviluppare la creativit\u00e0 per trovare soluzioni all&#8217;inquinamento<\/p><p>3.Coinvolgere le famiglie a cambiare le loro abitudini e a non usare pi\u00f9 la plastica.<br \/>4.Creare un movimento di scuole impegnate per il cambiamento sociale volto al rispetto ambientale.<\/p>                                        <\/div>\n                                    <\/div>\n                                <\/div>\n\n\t\t\t\t\t\t\t                                <div class=\"eael-circle-item elementor-repeater-item-deca302\">\n                                    <div aria-controls=\"eael-interactive-2\" tabindex=\"0\" class=\"eael-circle-btn \" id=\"eael-circle-item-2\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<!-- Start URL support -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-btn-icon classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-icon-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-far-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg><span class=\"eael-circle-btn-txt\">Quando <\/span>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                                        \t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- End URL support -->\n                                        \n                                    <\/div>\n                                    <div id=\"eael-interactive-2\" aria-labelledby=\"eael-circle-item-2\" class=\"eael-circle-btn-content eael-circle-item-2 \">\n                                        <div class=\"eael-circle-content\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Il concorso inizia il 1\u00b0 marzo 2023 e termina il 31 marzo 2024<\/p>                                        <\/div>\n                                    <\/div>\n                                <\/div>\n\n\t\t\t\t\t\t\t                                <div class=\"eael-circle-item elementor-repeater-item-c995efd\">\n                                    <div aria-controls=\"eael-interactive-3\" tabindex=\"0\" class=\"eael-circle-btn \" id=\"eael-circle-item-3\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<!-- Start URL support -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-btn-icon \">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-icon-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-male\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M96 0c35.346 0 64 28.654 64 64s-28.654 64-64 64-64-28.654-64-64S60.654 0 96 0m48 144h-11.36c-22.711 10.443-49.59 10.894-73.28 0H48c-26.51 0-48 21.49-48 48v136c0 13.255 10.745 24 24 24h16v136c0 13.255 10.745 24 24 24h64c13.255 0 24-10.745 24-24V352h16c13.255 0 24-10.745 24-24V192c0-26.51-21.49-48-48-48z\"><\/path><\/svg><span class=\"eael-circle-btn-txt\">A chi si rivolge<\/span>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                                        \t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- End URL support -->\n                                        \n                                    <\/div>\n                                    <div id=\"eael-interactive-3\" aria-labelledby=\"eael-circle-item-3\" class=\"eael-circle-btn-content eael-circle-item-3 \">\n                                        <div class=\"eael-circle-content\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Ci saranno 3 categorie di studenti che potranno partecipare al concorso.<br \/>Non ci sono limiti al numero di team che possono partecipare per ogni scuola<\/p><p>dai\u00a0 5 ai 7 anni<br \/>dagli 8 ai 10 anni<br \/>dai 10 ai 13 anni<\/p>                                        <\/div>\n                                    <\/div>\n                                <\/div>\n\n\t\t\t\t\t\t\t                                <div class=\"eael-circle-item elementor-repeater-item-862c0b2\">\n                                    <div aria-controls=\"eael-interactive-4\" tabindex=\"0\" class=\"eael-circle-btn \" id=\"eael-circle-item-4\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<!-- Start URL support -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-btn-icon \">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-icon-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-bong\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M302.5 512c23.18 0 44.43-12.58 56-32.66C374.69 451.26 384 418.75 384 384c0-36.12-10.08-69.81-27.44-98.62L400 241.94l9.38 9.38c6.25 6.25 16.38 6.25 22.63 0l11.3-11.32c6.25-6.25 6.25-16.38 0-22.63l-52.69-52.69c-6.25-6.25-16.38-6.25-22.63 0l-11.31 11.31c-6.25 6.25-6.25 16.38 0 22.63l9.38 9.38-39.41 39.41c-11.56-11.37-24.53-21.33-38.65-29.51V63.74l15.97-.02c8.82-.01 15.97-7.16 15.98-15.98l.04-31.72C320 7.17 312.82-.01 303.97 0L80.03.26c-8.82.01-15.97 7.16-15.98 15.98l-.04 31.73c-.01 8.85 7.17 16.02 16.02 16.01L96 63.96v153.93C38.67 251.1 0 312.97 0 384c0 34.75 9.31 67.27 25.5 95.34C37.08 499.42 58.33 512 81.5 512h221zM120.06 259.43L144 245.56V63.91l96-.11v181.76l23.94 13.87c24.81 14.37 44.12 35.73 56.56 60.57h-257c12.45-24.84 31.75-46.2 56.56-60.57z\"><\/path><\/svg><span class=\"eael-circle-btn-txt\">Cosa fanno i ragazzi<\/span>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                                        \t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- End URL support -->\n                                        \n                                    <\/div>\n                                    <div id=\"eael-interactive-4\" aria-labelledby=\"eael-circle-item-4\" class=\"eael-circle-btn-content eael-circle-item-4 \">\n                                        <div class=\"eael-circle-content\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Gli alunni &#8211; i veri protagonisti del concorso &#8211; devono presentare il loro progetto ecologico su come salvare il pianeta in modo originale.<br \/><br \/><br \/><\/p>                                        <\/div>\n                                    <\/div>\n                                <\/div>\n\n\t\t\t\t\t\t\t                                <div class=\"eael-circle-item elementor-repeater-item-63b89cf\">\n                                    <div aria-controls=\"eael-interactive-5\" tabindex=\"0\" class=\"eael-circle-btn \" id=\"eael-circle-item-5\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<!-- Start URL support -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-btn-icon \">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-icon-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg><span class=\"eael-circle-btn-txt\">Cosa viene valutato<\/span>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                                        \t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- End URL support -->\n                                        \n                                    <\/div>\n                                    <div id=\"eael-interactive-5\" aria-labelledby=\"eael-circle-item-5\" class=\"eael-circle-btn-content eael-circle-item-5 \">\n                                        <div class=\"eael-circle-content\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Si valuteranno:<\/p><p>-le idee pi\u00f9 creative, concrete ed efficaci per salvare il pianeta<\/p><p>-inventiva dei bambini<\/p><p>-l&#8217;inclusione e la coesione del team<\/p><p>-l&#8217;impatto dell&#8217;idea sull&#8217;ambiente<\/p><p>-funzionalit\u00e0 dell&#8217;invenzione<\/p><p>&#8211;<\/p>                                        <\/div>\n                                    <\/div>\n                                <\/div>\n\n\t\t\t\t\t\t\t                                <div class=\"eael-circle-item elementor-repeater-item-61c5545\">\n                                    <div aria-controls=\"eael-interactive-6\" tabindex=\"0\" class=\"eael-circle-btn \" id=\"eael-circle-item-6\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<!-- Start URL support -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-btn-icon \">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-circle-icon-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fas-hands-helping\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 192H336v56c0 39.7-32.3 72-72 72s-72-32.3-72-72V126.4l-64.9 39C107.8 176.9 96 197.8 96 220.2v47.3l-80 46.2C.7 322.5-4.6 342.1 4.3 357.4l80 138.6c8.8 15.3 28.4 20.5 43.7 11.7L231.4 448H368c35.3 0 64-28.7 64-64h16c17.7 0 32-14.3 32-32v-64h8c13.3 0 24-10.7 24-24v-48c0-13.3-10.7-24-24-24zm147.7-37.4L555.7 16C546.9.7 527.3-4.5 512 4.3L408.6 64H306.4c-12 0-23.7 3.4-33.9 9.7L239 94.6c-9.4 5.8-15 16.1-15 27.1V248c0 22.1 17.9 40 40 40s40-17.9 40-40v-88h184c30.9 0 56 25.1 56 56v28.5l80-46.2c15.3-8.9 20.5-28.4 11.7-43.7z\"><\/path><\/svg><span class=\"eael-circle-btn-txt\">Cosa fanno i docenti<\/span>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                                        \t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- End URL support -->\n                                        \n                                    <\/div>\n                                    <div id=\"eael-interactive-6\" aria-labelledby=\"eael-circle-item-6\" class=\"eael-circle-btn-content eael-circle-item-6 \">\n                                        <div class=\"eael-circle-content\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Raccolgono materiali e risorse utilizzate per introdurre la tematica ai bambini e ai ragazzi.<\/p><p>Supportano i bambini (senza sostituirsi a loro) nella raccolta di disegni, foto, video o registrazioni di attivit\u00e0<\/p>                                        <\/div>\n                                    <\/div>\n                                <\/div>\n\n\t\t\t\t\t\t\t\n                        <\/div>\n                    <\/div>\n                <\/div>\n\n\t\t\t\n        <\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-667df2f elementor-section-boxed ang-section-padding-initial elementor-section-height-default elementor-section-height-default elementor-repeater-item-none elementor-repeater-item-none_hover\" data-id=\"667df2f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-286c6ff elementor-repeater-item-none elementor-repeater-item-none_hover\" data-id=\"286c6ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5b2a5d elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"f5b2a5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Se siete interessati a partecipare a questa iniziativa avete tempo fino al 31 marzo 2023 e potete iscrivervi\u00a0 cliccando qui sotto\u00a0 ( insegnanti iscrivono i team )<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-aac9c60 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-parent\" data-id=\"aac9c60\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-131d6c0 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"131d6c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Link ai lavori presentati per il concorso <a href=\"https:\/\/schoolplasticfreemovement.org\/works-presented-for-the-concourse\/\" target=\"_blank\" rel=\"noopener\">Link to the page<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Presentazione del nuovo concorso \u00abGiovani scienziati che vogliono salvare il pianeta\u00bb<\/p>\n","protected":false},"author":4463,"featured_media":7348,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"_eb_attr":"","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[23,26,30,248,253],"tags":[],"class_list":["post-7346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-creativity","category-news","category-activities","category-high-green-tide","category-activities-in-italy-activities-in-lithuania"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2023\/01\/bambini-esplosione.jpg?fit=500%2C500&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbDhrA-1Uu","_links":{"self":[{"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/posts\/7346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/users\/4463"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/comments?post=7346"}],"version-history":[{"count":124,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/posts\/7346\/revisions"}],"predecessor-version":[{"id":11062,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/posts\/7346\/revisions\/11062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/media\/7348"}],"wp:attachment":[{"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/media?parent=7346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/categories?post=7346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/tags?post=7346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}