{"id":5766,"date":"2021-12-15T13:56:29","date_gmt":"2021-12-15T12:56:29","guid":{"rendered":"https:\/\/schoolplasticfreemovement.org\/?p=5766"},"modified":"2021-12-15T14:07:52","modified_gmt":"2021-12-15T13:07:52","slug":"actividad-spem-deja-tu-huella","status":"publish","type":"post","link":"https:\/\/schoolplasticfreemovement.org\/es\/actividad-spem-deja-tu-huella\/","title":{"rendered":"Actividad SPEM: Deja tu huella"},"content":{"rendered":"\n<div><div>\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"569\" height=\"180\" data-attachment-id=\"5347\" data-permalink=\"https:\/\/schoolplasticfreemovement.org\/es\/5346-2\/spem_webbanner\/\" data-orig-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/06\/SPEM_WebBanner.gif?fit=569%2C180&amp;ssl=1\" data-orig-size=\"569,180\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"SPEM_WebBanner\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/06\/SPEM_WebBanner.gif?fit=569%2C180&amp;ssl=1\" class=\"wp-image-5347\" src=\"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/06\/SPEM_WebBanner.gif?resize=569%2C180\" alt=\"\" \/><\/figure>\n<p style=\"text-align: right;\"><span style=\"font-size: 12px;\"><em>Esta actividad ha sido realizada por el profesor <strong>Miguel Corb\u00ed Santamar\u00eda<\/strong>\u00a0dentro de la<\/em><\/span><br \/><span style=\"font-size: 12px;\"><em>unidad did\u00e1ctica \u201cUn planeta plastificado\u201d, llevada a cabo en Burgos (Espa\u00f1a)<\/em><\/span><br \/><span style=\"font-size: 12px;\"><em>durante los meses de octubre y noviembre de 2021.<\/em><\/span><\/p>\n<table style=\"border-style: solid; width: 100%; border-color: #000000;\" width=\"100%\">\n<tbody>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>T\u00edtulo de la actividad \/ pr\u00e1ctica<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Deja tu huella<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Origen de la actividad<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Es la cuarta sesi\u00f3n del m\u00f3dulo \u201cUn planeta plastificado\u201d, donde se pretende asentar los conceptos desarrollados en sesiones anteriores.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Edad de los estudiantes<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a09-10 a\u00f1os<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Grupo objetivo (tipo de alumnos, tama\u00f1o del grupo)<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Estudiantes de 4\u00ba-5\u00ba de Educaci\u00f3n Primaria con altas capacidades. El n\u00famero m\u00e1ximo para desarrollar la actividad es de 10 estudiantes.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Asignaturas escolares + temas afectados<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Tecnolog\u00eda, arte y creatividad.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Objetivos educativos de la pr\u00e1ctica<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Consolidar los conocimientos adquiridos en sesiones anteriores por medio de una propuesta pr\u00e1ctica y creativa.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Duraci\u00f3n<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a02-2,5 horas<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Lugar<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Sal\u00f3n de actos o espacio amplio y libre de obst\u00e1culos.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Materiales \/ Recursos \/ requisitos t\u00e9cnicos<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bastidores y tela.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 C\u00e1mara de v\u00eddeo y tr\u00edpode.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Foco.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Material de oficina (papel, bol\u00edgrafo, tijeras, celo, etc.)<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Cartulina y cart\u00f3n.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" rowspan=\"4\" width=\"18%\">\n<p><strong>Descripci\u00f3n de la actividad<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Preparaci\u00f3n:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La pr\u00e1ctica consiste en la elaboraci\u00f3n de un v\u00eddeo con un mensaje relacionado con los conceptos tratados durante el taller, por medio de la t\u00e9cnica de teatro de sombras.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En un espacio amplio se dispone el set con un foco potente (preferiblemente con difusor) a un lado de los bastidores con la tela, y al otro, la c\u00e1mara con tr\u00edpode.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>Fase principal:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Creaci\u00f3n de la historia: los participantes sobre el mensaje que quieren transmitir. Posteriormente, se desarrolla la historia con un guion, en funci\u00f3n del n\u00famero de participantes y las habilidades de cada uno.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Reparto de roles: se distribuye a los estudiantes entre las diferentes tareas a desarrollar (direcci\u00f3n, guion, atrezo y t\u00e9cnicos).<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Preparaci\u00f3n del atrezo: los participantes desarrollan el material necesario de representaci\u00f3n, con la ayuda de las cartulinas y cartones.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Preparaci\u00f3n de medios t\u00e9cnicos: se disponen todos medios t\u00e9cnicos y sus posibilidades.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ensayo.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Grabaci\u00f3n de sonido.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Grabaci\u00f3n de imagen.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>Conclusiones:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Esta actividad permite que los participantes asuman responsabilidades en una tarea creativa com\u00fan.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>Otros elementos (opcional):<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Evaluaci\u00f3n<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>\u00a0Encuesta de conocimientos antes y despu\u00e9s del m\u00f3dulo, as\u00ed como encuesta de satisfacci\u00f3n.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Enlace a recursos externos \u00fatiles (opcional)<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Enlace a los resultados de la actividad (v\u00eddeo, fotos, proyectos, etc.)<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>Representaci\u00f3n resultante: <a href=\"https:\/\/universidaddeburgos-my.sharepoint.com\/:v:\/g\/personal\/mcorbi_ubu_es\/EUZOTduLdJFPo_qo_DLfeX8B1wuW1SxUDoO10jU-QfWU3w?e=aNkOmj\">https:\/\/universidaddeburgos-my.sharepoint.com\/:v:\/g\/personal\/mcorbi_ubu_es\/EUZOTduLdJFPo_qo_DLfeX8B1wuW1SxUDoO10jU-QfWU3w?e=aNkOmj<\/a><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"18%\">\n<p><strong>Consejos para educadores \/ antecedentes te\u00f3ricos o contexto curricular<\/strong><\/p>\n<\/td>\n<td style=\"border-style: solid; border-color: #000000;\" width=\"81%\">\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Es recomendable que las orientaciones del educador se limiten lo m\u00e1s posible, permitiendo que el resultado sea propiedad de los estudiantes.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4293,"featured_media":5767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[30,70,255],"tags":[],"class_list":["post-5766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activities","category-scuole-senza-plastica","category-activities-in-spain"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/schoolplasticfreemovement.org\/wp-content\/uploads\/2021\/12\/istockphoto-1337205816-612x612-1.jpg?fit=612%2C408&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbDhrA-1v0","_links":{"self":[{"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/posts\/5766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/users\/4293"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/comments?post=5766"}],"version-history":[{"count":3,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/posts\/5766\/revisions"}],"predecessor-version":[{"id":5774,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/posts\/5766\/revisions\/5774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/media\/5767"}],"wp:attachment":[{"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/media?parent=5766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/categories?post=5766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schoolplasticfreemovement.org\/es\/wp-json\/wp\/v2\/tags?post=5766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}